{"id":8119,"date":"2026-03-10T13:33:13","date_gmt":"2026-03-10T12:33:13","guid":{"rendered":"https:\/\/zijda.nl\/yachthafen\/"},"modified":"2026-07-24T13:42:29","modified_gmt":"2026-07-24T11:42:29","slug":"yachthafen","status":"publish","type":"page","link":"https:\/\/zijda.nl\/de\/yachthafen\/","title":{"rendered":"Yachthafen"},"content":{"rendered":"<p>Yachthafen<\/p>\n<p>Banner:<br \/>\n  Boventitel: \u00dcberwinterung, Wartung und Reparatur<br \/>\n  Titel: Yachthafen<\/p>\n<p>Blokken:<br \/>\n  Blokken:<br \/>\n    [Content enkel center]<br \/>\n      Boventitel: Unsere Flotte<br \/>\n      Titel: Yachthafen Friesland<br \/>\n      Tekst: Der Yachthafen von Zijda Yachting \/ Marina Jirnsum befindet sich in Jirnsum. M\u00f6chten Sie die Pl\u00e4tze im Yachthafen nutzen? Dann nehmen Sie bitte Kontakt mit uns auf oder besuchen Sie die Website von Marina Jirnsum. Wir bieten unter anderem Winterlager im Freien im Hafen im Wasser, Reparatur- und Wartungsarbeiten usw. an.<br \/>\n    [Content afbeelding]<br \/>\n      Boventitel: + 200 Liegepl\u00e4tze<br \/>\n      Titel: Liegepl\u00e4tze<br \/>\n      Tekst: Mit mehr als 200 Liegepl\u00e4tzen verf\u00fcgen wir \u00fcber die Kapazit\u00e4ten, eine betr\u00e4chtliche Anzahl von Booten und Yachten unterzubringen. Dabei unterscheiden wir zwischen festen und flexiblen Liegepl\u00e4tzen. Der Unterschied? Einen flexiblen Liegeplatz mieten Sie f\u00fcr einen kurzen Zeitraum, w\u00e4hrend Sie einen festen Liegeplatz f\u00fcr eine ganze Saison mieten. Um die festen Liegepl\u00e4tze nicht zu sehr durch ankommende und abfahrende Yachten zu belasten, sind diese Pl\u00e4tze voneinander getrennt.<br \/>\n      Tekst met schaduw: 1<br \/>\n      Toon blok over img: 1<br \/>\n      Blok over img:<br \/>\n        Titel: + 200 Liegepl\u00e4tze<br \/>\n    [Afbeelding content]<br \/>\n      Boventitel: + 200 Liegepl\u00e4tze<br \/>\n      Titel: Ausstattung<br \/>\n      Tekst: Wenn Sie Hilfe bei Angelegenheiten rund um unseren Yachthafen ben\u00f6tigen, k\u00f6nnen Sie sich jederzeit an unsere besetzte Rezeption wenden, die w\u00e4hrend der Saison (1. April bis 1. Oktober) ge\u00f6ffnet ist. Au\u00dferdem stehen Ihnen dort Parkpl\u00e4tze, ein Sanit\u00e4rgeb\u00e4ude, M\u00fcllcontainer, Servicetechniker, Tankstellen, Reinigungsdienste, eine Bootsrampe und sogar eine Tierweide zur Verf\u00fcgung. Kurz gesagt: Unser Yachthafen ist mit den besten Einrichtungen ausgestattet.<br \/>\n    [Content afbeelding]<br \/>\n      Boventitel: Your yacht, your way<br \/>\n      Titel: Reparatur und Wartung<br \/>\n      Tekst: M\u00f6chten Sie Ihr Boot gerne in einwandfreiem Zustand halten? Dann sind die notwendigen Reparaturen und Wartungsarbeiten an Ihrem Boot unvermeidlich. Zijda Yachting steht Ihnen bei allen anfallenden Arbeiten zur Seite, wie zum Beispiel: Lackierarbeiten Unterwasserbehandlung Tischlerarbeiten Motorwartung Komplette Renovierung<br \/>\n      Toon blok over img: 1<br \/>\n      Blok over img:<br \/>\n        Tekst: Wir k\u00fcmmern uns mit viel Liebe und Sorgfalt um Ihr Boot. Zijda Yachting garantiert ein optimales Ergebnis. Wir sorgen daf\u00fcr, dass Ihr Boot wieder in einwandfreiem Zustand an Sie zur\u00fcckgegeben wird.<br \/>\n    [Content center slider]<br \/>\n      Boventitel: Marina Jirnsum<br \/>\n      Titel: Preise f\u00fcr den Yachthafen<br \/>\n      Tekst: M\u00f6chten Sie mehr \u00fcber unseren Yachthafen in Friesland erfahren? Das ist m\u00f6glich! Wir empfehlen Ihnen, die Website von Marina Jirnsum zu besuchen, die speziell dazu dient, Sie \u00fcber unseren Yachthafen zu informieren. Dort erfahren Sie mehr \u00fcber die Einrichtungen, die Umgebung, die Liegepl\u00e4tze und die Preise unseres Yachthafens. Die Liegepl\u00e4tze sind ab 930 \u20ac pro Saison verf\u00fcgbar. In unserem Yachthafen ist Ihre Yacht oder Ihr Boot sicher vor Diebstahl und wetterbedingten Sch\u00e4den gesch\u00fctzt. Das ist also auf jeden Fall eine \u00dcberlegung wert! Wir hoffen, Sie bald in Jirnsum begr\u00fc\u00dfen zu d\u00fcrfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yachthafen Banner: Boventitel: \u00dcberwinterung, Wartung und Reparatur Titel: Yachthafen Blokken: Blokken: [Content enkel center] Boventitel: Unsere Flotte Titel: Yachthafen Friesland Tekst: Der Yachthafen von Zijda Yachting \/ Marina Jirnsum befindet sich in Jirnsum. M\u00f6chten Sie die Pl\u00e4tze im Yachthafen nutzen? Dann nehmen Sie bitte Kontakt mit uns auf oder besuchen Sie die Website von Marina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8119","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/pages\/8119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/comments?post=8119"}],"version-history":[{"count":1,"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/pages\/8119\/revisions"}],"predecessor-version":[{"id":9872,"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/pages\/8119\/revisions\/9872"}],"wp:attachment":[{"href":"https:\/\/zijda.nl\/de\/wp-json\/wp\/v2\/media?parent=8119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}